{"id":170,"count":1,"description":"","link":"https:\/\/createomoto.com\/Studios\/tag\/digital\/","name":"Digital","slug":"digital","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital - Createomoto Studios: Fueling the Future of Creative Content<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital - Createomoto Studios: Fueling the Future of Creative Content\" \/>\n<meta property=\"og:url\" content=\"https:\/\/createomoto.com\/Studios\/tag\/digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Createomoto Studios: Fueling the Future of Creative Content\" \/>\n<meta property=\"og:image\" content=\"https:\/\/createomoto.com\/Studios\/wp-content\/uploads\/2021\/03\/Createomoto-Profile-BG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@createomoto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/tag\\\/digital\\\/\",\"url\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/tag\\\/digital\\\/\",\"name\":\"Digital - Createomoto Studios: Fueling the Future of Creative Content\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/tag\\\/digital\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/tag\\\/digital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/#website\",\"url\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/\",\"name\":\"Createomoto Studios: Fueling the Future of Creative Content\",\"description\":\"Share Your Creatives With The World!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/createomoto.com\\\/Studios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital - Createomoto Studios: Fueling the Future of Creative Content","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Digital - Createomoto Studios: Fueling the Future of Creative Content","og_url":"https:\/\/createomoto.com\/Studios\/tag\/digital\/","og_site_name":"Createomoto Studios: Fueling the Future of Creative Content","og_image":[{"width":1500,"height":500,"url":"https:\/\/createomoto.com\/Studios\/wp-content\/uploads\/2021\/03\/Createomoto-Profile-BG.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@createomoto","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/createomoto.com\/Studios\/tag\/digital\/","url":"https:\/\/createomoto.com\/Studios\/tag\/digital\/","name":"Digital - Createomoto Studios: Fueling the Future of Creative Content","isPartOf":{"@id":"https:\/\/createomoto.com\/Studios\/#website"},"breadcrumb":{"@id":"https:\/\/createomoto.com\/Studios\/tag\/digital\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/createomoto.com\/Studios\/tag\/digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/createomoto.com\/Studios\/"},{"@type":"ListItem","position":2,"name":"Digital"}]},{"@type":"WebSite","@id":"https:\/\/createomoto.com\/Studios\/#website","url":"https:\/\/createomoto.com\/Studios\/","name":"Createomoto Studios: Fueling the Future of Creative Content","description":"Share Your Creatives With The World!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/createomoto.com\/Studios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/createomoto.com\/Studios\/wp-json\/wp\/v2\/tags\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/createomoto.com\/Studios\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/createomoto.com\/Studios\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/createomoto.com\/Studios\/wp-json\/wp\/v2\/posts?tags=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}